{"id":17593,"date":"2022-03-11T14:01:38","date_gmt":"2022-03-11T12:01:38","guid":{"rendered":"\/"},"modified":"2026-06-18T18:16:17","modified_gmt":"2026-06-18T16:16:17","slug":"dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off","status":"publish","type":"post","link":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/","title":{"rendered":"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF"},"content":{"rendered":"<p>Tras su \u00e9xito el pasado a\u00f1o, Sala BBK subir\u00e1 el tel\u00f3n en abril a las propuestas art\u00edsticas m\u00e1s arriesgadas, rompedoras e innovadoras. La cita con estas producciones alejadas de los circuitos convencionales se concentrar\u00e1 durante dos fines de semana en la segunda edici\u00f3n del BBK OFF FESTIVAL, un certamen alternativo que consolida la apuesta de la Sala por acercarse a nuevos p\u00fablicos y tendencias culturales.<\/p>\n<p>El festival, que este a\u00f1o ha recibido m\u00e1s del doble de solicitudes que en la pasada edici\u00f3n, pondr\u00e1 en escena <strong>16 propuestas elegidas por un jurado experto de entre las 159 presentadas.<\/strong> Nueve pa\u00edses (Argentina, Chipre, Colombia, Rusia o Cuba, entre otros) y 16 comunidades aut\u00f3nomas distintas han presentado solicitudes en esta segunda edici\u00f3n del BBK OFF; una edici\u00f3n que llega cargada de riesgo, investigaci\u00f3n, audacia y humor.<\/p>\n<p>Por primera vez, el festival amplia su c\u00edrculo de acci\u00f3n para abrirse al estado espa\u00f1ol y tendr\u00e1, como novedad, varias piezas internacionales invitadas fuera de la programaci\u00f3n oficial gracias al programa europeo <strong>Perform Europe.<\/strong><\/p>\n<p>\u201cBillenium\u201d y \u201cTo those born later\u201d son las dos piezas del proyecto \u201cPerforming Futures\u201d, un proyecto seleccionado por este programa europeo junto con el \u00abInternational Theatre Days in Belgrade\u00bb y el \u00abPLACCC Festival\u00bb (Bilbao- Belgrado- Budapest) que podr\u00e1n verse en el BBK OFF.<\/p>\n<p>Asimismo, y tras la fant\u00e1stica acogida en la pasada edici\u00f3n, el festival abrir\u00e1 dos actividades gratuitas para todas aquellas personas interesadas en desarrollar proyectos culturales: la primera, de la mano del Paul Clarke y Jessica Hoffman tendr\u00e1 por t\u00edtulo \u201c<strong>Digital Transformation in Performance\u201d<\/strong> y ser\u00e1 una charla centrada en distintos aspectos tecnol\u00f3gicos aplicados a las artes esc\u00e9nicas. La segunda, ser\u00e1 un taller impartido por Jemima Cano bajo el t\u00edtulo de <strong>\u201c<\/strong><strong>Producci\u00f3n Cultural sXXI: <\/strong><strong>como ser green y no morir en el intento<\/strong>\u201d y har\u00e1 hincapi\u00e9 en c\u00f3mo abordar la sostenibilidad en nuestras pr\u00e1cticas esc\u00e9nicas.<\/p>\n<p>Otra de las novedades ser\u00e1 la emisi\u00f3n en pantalla grande de la <strong>\u00f3pera ukraniana <\/strong><strong>CHORNOBYLDORF<\/strong>, una inciativa que suma al BBK OFF la voluntad de Obra Social BBK por ayudar al pueblo ucranianio que tanto est\u00e1 sufriendo en estos momentos. La \u00f3pera, que podr\u00e1 verse con subt\u00edtulos en ingl\u00e9s, se presenta como una actividad solidaria cuya recaudaci\u00f3n de taquilla ir\u00e1 a parar \u00edntegramente a los artistas de esta producci\u00f3n.<\/p>\n<p>M\u00e1s informaci\u00f3n: <a href=\"https:\/\/salabbk.bbk.eus\/amorante-ghau\/\">www.salabbk.bbk.eus<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras su \u00e9xito el pasado a\u00f1o, Sala BBK subir\u00e1 el  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[566],"tags":[],"class_list":["post-17593","post","type-post","status-publish","format-standard","hentry","category-cultura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF - Actualidad - BBK<\/title>\n<meta name=\"description\" content=\"Tras su \u00e9xito el pasado a\u00f1o, Sala BBK subir\u00e1 el tel\u00f3n en abril a las propuestas art\u00edsticas m\u00e1s arriesgadas, rompedoras e innovadoras. La cita con estas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF - Actualidad - BBK\" \/>\n<meta property=\"og:description\" content=\"Tras su \u00e9xito el pasado a\u00f1o, Sala BBK subir\u00e1 el tel\u00f3n en abril a las propuestas art\u00edsticas m\u00e1s arriesgadas, rompedoras e innovadoras. La cita con estas\" \/>\n<meta property=\"og:url\" content=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/\" \/>\n<meta property=\"og:site_name\" content=\"BBK\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBKeus?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-11T12:01:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T16:16:17+00:00\" \/>\n<meta name=\"author\" content=\"\u00darsula L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:site\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00darsula L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\\\/\"},\"author\":{\"name\":\"\u00darsula L\u00f3pez\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/317821b3a0d0178af253b98b08027fda\"},\"headline\":\"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF\",\"datePublished\":\"2022-03-11T12:01:38+00:00\",\"dateModified\":\"2026-06-18T16:16:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\\\/\"},\"wordCount\":425,\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\\\/\",\"name\":\"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF - Actualidad - BBK\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\"},\"datePublished\":\"2022-03-11T12:01:38+00:00\",\"dateModified\":\"2026-06-18T16:16:17+00:00\",\"description\":\"Tras su \u00e9xito el pasado a\u00f1o, Sala BBK subir\u00e1 el tel\u00f3n en abril a las propuestas art\u00edsticas m\u00e1s arriesgadas, rompedoras e innovadoras. La cita con estas\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"name\":\"BBK\",\"description\":\"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.\",\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\",\"name\":\"BBK Fundazioa\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"contentUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"width\":1845,\"height\":784,\"caption\":\"BBK Fundazioa\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BBKeus?fref=ts\",\"https:\\\/\\\/x.com\\\/BBK_eus\",\"https:\\\/\\\/www.instagram.com\\\/bbk_eus\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BBKwebTV\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-bbk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/317821b3a0d0178af253b98b08027fda\",\"name\":\"\u00darsula L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"caption\":\"\u00darsula L\u00f3pez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF - Actualidad - BBK","description":"Tras su \u00e9xito el pasado a\u00f1o, Sala BBK subir\u00e1 el tel\u00f3n en abril a las propuestas art\u00edsticas m\u00e1s arriesgadas, rompedoras e innovadoras. La cita con estas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/","og_locale":"es_ES","og_type":"article","og_title":"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF - Actualidad - BBK","og_description":"Tras su \u00e9xito el pasado a\u00f1o, Sala BBK subir\u00e1 el tel\u00f3n en abril a las propuestas art\u00edsticas m\u00e1s arriesgadas, rompedoras e innovadoras. La cita con estas","og_url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/","og_site_name":"BBK","article_publisher":"https:\/\/www.facebook.com\/BBKeus?fref=ts","article_published_time":"2022-03-11T12:01:38+00:00","article_modified_time":"2026-06-18T16:16:17+00:00","author":"\u00darsula L\u00f3pez","twitter_card":"summary_large_image","twitter_creator":"@BBK_eus","twitter_site":"@BBK_eus","twitter_misc":{"Escrito por":"\u00darsula L\u00f3pez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/#article","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/"},"author":{"name":"\u00darsula L\u00f3pez","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/317821b3a0d0178af253b98b08027fda"},"headline":"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF","datePublished":"2022-03-11T12:01:38+00:00","dateModified":"2026-06-18T16:16:17+00:00","mainEntityOfPage":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/"},"wordCount":425,"publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"articleSection":["Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/","name":"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF - Actualidad - BBK","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website"},"datePublished":"2022-03-11T12:01:38+00:00","dateModified":"2026-06-18T16:16:17+00:00","description":"Tras su \u00e9xito el pasado a\u00f1o, Sala BBK subir\u00e1 el tel\u00f3n en abril a las propuestas art\u00edsticas m\u00e1s arriesgadas, rompedoras e innovadoras. La cita con estas","breadcrumb":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/dieciseis-propuestas-arriesgadas-e-innovadoras-en-la-segunda-edicion-del-bbk-off\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/"},{"@type":"ListItem","position":2,"name":"DIECISEIS PROPUESTAS ARRIESGADAS E INNOVADORAS EN LA SEGUNDA EDICI\u00d3N DEL BBK OFF"}]},{"@type":"WebSite","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","name":"BBK","description":"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.","publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization","name":"BBK Fundazioa","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","contentUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","width":1845,"height":784,"caption":"BBK Fundazioa"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BBKeus?fref=ts","https:\/\/x.com\/BBK_eus","https:\/\/www.instagram.com\/bbk_eus\/?hl=es","https:\/\/www.youtube.com\/user\/BBKwebTV","https:\/\/www.linkedin.com\/company\/fundacion-bbk\/"]},{"@type":"Person","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/317821b3a0d0178af253b98b08027fda","name":"\u00darsula L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","caption":"\u00darsula L\u00f3pez"}}]}},"_links":{"self":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/17593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/comments?post=17593"}],"version-history":[{"count":0,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/17593\/revisions"}],"wp:attachment":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/media?parent=17593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/categories?post=17593"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/tags?post=17593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}