{"id":18859,"date":"2022-07-01T15:08:17","date_gmt":"2022-07-01T13:08:17","guid":{"rendered":"\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/"},"modified":"2026-06-18T18:14:01","modified_gmt":"2026-06-18T16:14:01","slug":"bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia","status":"publish","type":"post","link":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/","title":{"rendered":"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA"},"content":{"rendered":"<p>BBK ha dado hoy el pistoletazo de salida al proyecto \u201cHerriz Herri\u201d, una iniciativa en colaboraci\u00f3n con m\u00e1s de 85 ayuntamientos de Bizkaia a trav\u00e9s de la cual la entidad llevar\u00e1 a cabo diversas acciones de impacto social positivo durante 2022. La iniciativa cuenta con una inversi\u00f3n de m\u00e1s de 16 millones de euros por parte de la entidad. La primera parada de este proyecto es Trapagaran, donde BBK ha firmado un acuerdo con el ayuntamiento para impulsar conjuntamente los siguientes proyectos: Dantzari ibiltaria, Invisible soledad, Azokak, La ruta del arte y Digitalizaci\u00f3n del deporte. En el evento de presentaci\u00f3n han estado presentes Gorka Mart\u00ednez, director general de BBK, Xabier Cu\u00e9llar, alcalde de Trapagaran y la concejala de Cultura, Silvia Mera.<\/p>\n<p>Mientras que la iniciativa La ruta del arte, que impulsa el acercamiento del arte y la cultura al territorio de Bizkaia y a la ciudadan\u00eda, ya pas\u00f3 por Trapagaran entre el 24 y 31 de mayo, recientemente se acaba de poner en marcha el proyecto para la Digitalizaci\u00f3n del deporte, a trav\u00e9s de cual BBK incorporar\u00e1 innovaciones tecnol\u00f3gicas en las instalaciones deportivas locales, en concreto en el campo de f\u00fatbol Errotarte y el polideportivo municipal.<\/p>\n<p>Tras el verano, Trapagaran acoger\u00e1 Dantzari ibiltaria, una actividad para fomentar el baile tradicional vasco entre la ciudadan\u00eda.\u00a0 Tendr\u00e1 lugar el 2 de septiembre en la plaza Llano a las 18.30 horas. Esta romer\u00eda, dinamizada por Aiko Taldea, animar\u00e1 a los locales a participar en esta experiencia con m\u00fasica en directo. Adem\u00e1s, de manera inclusiva, se dar\u00e1n indicaciones para que todos y todas puedan disfrutar de la danza durante la jornada.<\/p>\n<p>En septiembre llegar\u00e1 a Trapagaran Invisible soledad, la exitosa iniciativa que BBK puso en marcha en 2019 con el objetivo de concienciar a la sociedad sobre la soledad no deseada en personas mayores. En esta ocasi\u00f3n, la escultura hiperrealista de Mercedes, obra del artista mexicano Rub\u00e9n Orozco, se ubicar\u00e1 en la Avenida Primero de Mayo. Asimismo, en octubre se pondr\u00e1n en marcha unas jornadas de concienciaci\u00f3n y divulgaci\u00f3n para activar pautas que ayuden a evitar situaciones de soledad no deseada.<\/p>\n<p>Paralelamente, se llevar\u00e1 a cabo un curso con p\u00edldoras formativas dirigido a las personas mayores para abordar la brecha digital en la gesti\u00f3n de la banca online, de la mano de Sasoiko-Secot y Kutxabank.<\/p>\n<p>Por otra parte, el 6 de noviembre se celebrar\u00e1 la XXI Feria Agr\u00edcola- Ganadera de la Arboleda, una cita que cuenta con la colaboraci\u00f3n de BBK a trav\u00e9s de su iniciativa de apoyo al sector primario y a la venta de productos de cercan\u00eda Azokak.<\/p>\n<p>Con este proyecto, BBK muestra su compromiso con la cohesi\u00f3n y el bienestar de los y las bizkaitarras, tal y como ha explicado Gorka Mart\u00ednez, director general de BBK durante la presentaci\u00f3n del convenio: \u201c<em>Gracias a Herriz Herri vamos a trabajar mano a mano con ayuntamientos y con diferentes agentes sociales locales para impulsar acciones conjuntas de impacto social positivo. En BBK somos partidarios de generar una red en la que diferentes actores trabajemos juntos para el bien com\u00fan y as\u00ed poder construir una Bizkaia para todos y todas, inclusiva, pr\u00f3spera, cohesionada y sostenible. Con este programa vamos a llevar al m\u00e1ximo de municipios de Bizkaia posibles iniciativas que abogan por la igualdad de oportunidades, la integraci\u00f3n social y el desarrollo del territorio, pensadas desde el prisma de la competitividad sostenible y los ODS marcados en la agenda 2030, para que el conjunto de la ciudadan\u00eda de Bizkaia, resida donde resida, pueda aprovechar todo lo que ofrece la obra social de BBK, que con una media de inversi\u00f3n de 38 millones anuales es la primera obra social del Estado en inversi\u00f3n por habitante. Todo ello con el objetivo de dejar a las generaciones venideras un mundo mejor\u201d<\/em>.<\/p>\n<p>Por su parte, Xabier Cu\u00e9llar, alcalde de Trapagaran ha manifestado durante esta presentaci\u00f3n que \u00abeste tipo de iniciativas, gracias a la colaboraci\u00f3n de BBK y el programa &#8216;Herriz Herri&#8217;, son muy interesantes, ya que acercan al p\u00fablico acciones culturales y de otros \u00e1mbitos, que abogan por la igualdad de oportunidades, la integraci\u00f3n social y el desarrollo del territorio\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trapagaran es la primera localidad donde la entidad activa este programa que incluye los proyectos Dantzari ibiltaria, Invisible soledad, Azokak, La ruta del arte o Digitalizaci\u00f3n del deporte, entre otros, impulsados desde BBK<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[567],"tags":[],"class_list":["post-18859","post","type-post","status-publish","format-standard","hentry","category-personas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA - Actualidad - BBK<\/title>\n<meta name=\"description\" content=\"Trapagaran es la primera localidad donde la entidad activa este programa que incluye los proyectos Dantzari ibiltaria, Invisible soledad, Azokak, La ruta del arte o Digitalizaci\u00f3n del deporte, entre otros, impulsados desde BBK\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA - Actualidad - BBK\" \/>\n<meta property=\"og:description\" content=\"Trapagaran es la primera localidad donde la entidad activa este programa que incluye los proyectos Dantzari ibiltaria, Invisible soledad, Azokak, La ruta del arte o Digitalizaci\u00f3n del deporte, entre otros, impulsados desde BBK\" \/>\n<meta property=\"og:url\" content=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/\" \/>\n<meta property=\"og:site_name\" content=\"BBK\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBKeus?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-01T13:08:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T16:14:01+00:00\" \/>\n<meta name=\"author\" content=\"Sonia Egea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:site\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia Egea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\\\/\"},\"author\":{\"name\":\"Sonia Egea\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/1e591116b03708dd7b1aa17bfe896d11\"},\"headline\":\"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA\",\"datePublished\":\"2022-07-01T13:08:17+00:00\",\"dateModified\":\"2026-06-18T16:14:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\\\/\"},\"wordCount\":736,\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"articleSection\":[\"Personas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\\\/\",\"name\":\"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA - Actualidad - BBK\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\"},\"datePublished\":\"2022-07-01T13:08:17+00:00\",\"dateModified\":\"2026-06-18T16:14:01+00:00\",\"description\":\"Trapagaran es la primera localidad donde la entidad activa este programa que incluye los proyectos Dantzari ibiltaria, Invisible soledad, Azokak, La ruta del arte o Digitalizaci\u00f3n del deporte, entre otros, impulsados desde BBK\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"name\":\"BBK\",\"description\":\"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.\",\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\",\"name\":\"BBK Fundazioa\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"contentUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"width\":1845,\"height\":784,\"caption\":\"BBK Fundazioa\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BBKeus?fref=ts\",\"https:\\\/\\\/x.com\\\/BBK_eus\",\"https:\\\/\\\/www.instagram.com\\\/bbk_eus\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BBKwebTV\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-bbk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/1e591116b03708dd7b1aa17bfe896d11\",\"name\":\"Sonia Egea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x\",\"caption\":\"Sonia Egea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA - Actualidad - BBK","description":"Trapagaran es la primera localidad donde la entidad activa este programa que incluye los proyectos Dantzari ibiltaria, Invisible soledad, Azokak, La ruta del arte o Digitalizaci\u00f3n del deporte, entre otros, impulsados desde BBK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/","og_locale":"es_ES","og_type":"article","og_title":"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA - Actualidad - BBK","og_description":"Trapagaran es la primera localidad donde la entidad activa este programa que incluye los proyectos Dantzari ibiltaria, Invisible soledad, Azokak, La ruta del arte o Digitalizaci\u00f3n del deporte, entre otros, impulsados desde BBK","og_url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/","og_site_name":"BBK","article_publisher":"https:\/\/www.facebook.com\/BBKeus?fref=ts","article_published_time":"2022-07-01T13:08:17+00:00","article_modified_time":"2026-06-18T16:14:01+00:00","author":"Sonia Egea","twitter_card":"summary_large_image","twitter_creator":"@BBK_eus","twitter_site":"@BBK_eus","twitter_misc":{"Escrito por":"Sonia Egea","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/#article","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/"},"author":{"name":"Sonia Egea","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/1e591116b03708dd7b1aa17bfe896d11"},"headline":"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA","datePublished":"2022-07-01T13:08:17+00:00","dateModified":"2026-06-18T16:14:01+00:00","mainEntityOfPage":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/"},"wordCount":736,"publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"articleSection":["Personas"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/","name":"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA - Actualidad - BBK","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website"},"datePublished":"2022-07-01T13:08:17+00:00","dateModified":"2026-06-18T16:14:01+00:00","description":"Trapagaran es la primera localidad donde la entidad activa este programa que incluye los proyectos Dantzari ibiltaria, Invisible soledad, Azokak, La ruta del arte o Digitalizaci\u00f3n del deporte, entre otros, impulsados desde BBK","breadcrumb":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-presenta-en-trapagaran-el-programa-herriz-herri-para-trabajar-proyectos-de-impacto-social-positivo-junto-a-los-ayuntamientos-de-bizkaia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/"},{"@type":"ListItem","position":2,"name":"BBK PRESENTA EN TRAPAGARAN EL PROGRAMA \u201cHERRIZ HERRI\u201d PARA TRABAJAR PROYECTOS DE IMPACTO SOCIAL POSITIVO JUNTO A LOS AYUNTAMIENTOS DE BIZKAIA"}]},{"@type":"WebSite","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","name":"BBK","description":"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.","publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization","name":"BBK Fundazioa","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","contentUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","width":1845,"height":784,"caption":"BBK Fundazioa"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BBKeus?fref=ts","https:\/\/x.com\/BBK_eus","https:\/\/www.instagram.com\/bbk_eus\/?hl=es","https:\/\/www.youtube.com\/user\/BBKwebTV","https:\/\/www.linkedin.com\/company\/fundacion-bbk\/"]},{"@type":"Person","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/1e591116b03708dd7b1aa17bfe896d11","name":"Sonia Egea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x","caption":"Sonia Egea"}}]}},"_links":{"self":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/18859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/comments?post=18859"}],"version-history":[{"count":0,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/18859\/revisions"}],"wp:attachment":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/media?parent=18859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/categories?post=18859"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/tags?post=18859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}