{"id":19206,"date":"2022-09-13T12:41:04","date_gmt":"2022-09-13T10:41:04","guid":{"rendered":"\/"},"modified":"2026-06-18T18:12:22","modified_gmt":"2026-06-18T16:12:22","slug":"aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso","status":"publish","type":"post","link":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/","title":{"rendered":"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso"},"content":{"rendered":"<p>Este a\u00f1o, BBK propone a las personas mayores de 55 a\u00f1os que han finalizado su etapa laboral volver a las aulas para estudiar la lecci\u00f3n m\u00e1s importante: aprender a cuidarse para afrontar con plenitud la larga etapa vital que se abre ante ellas. Para ello, la entidad ha puesto en marcha AGEKIN SASOIKO, una formaci\u00f3n innovadora centrada en conocimientos y habilidades para la vida diaria, con el foco puesto en favorecer el autocuidado y las relaciones interpersonales. Las inscripciones est\u00e1n abiertas en la <a href=\"https:\/\/bbkytu.bbk.eus\/default.asp?idioma=ES\">web BBK Y TU<\/a> hasta el pr\u00f3ximo 30 de septiembre.<\/p>\n<p>En esta etapa de la vida, son muchas y muy diversas las preguntas que pueden surgir: \u00bfC\u00f3mo puedo protegerme de los peligros de internet? \u00bfQu\u00e9 pautas puedo seguir para mantener la salud? \u00bfC\u00f3mo puedo adaptar mi casa a esta nueva etapa? \u00bfC\u00f3mo conviene que organice mis asuntos financieros? \u00bfQu\u00e9 ventajas me ofrece la\u00a0 digitalizaci\u00f3n de la\u00a0 administraci\u00f3n? \u00bfQu\u00e9 puedo hacer ante una situaci\u00f3n de violencia? \u00bfC\u00f3mo puedo planificar mi futuro?<\/p>\n<p>AGEKIN SASOIKO dar\u00e1 respuesta a estas y a otras muchas cuestiones desde el pr\u00f3ximo d\u00eda 3 de octubre y durante todo el curso acad\u00e9mico 2022-2023, hasta el 31 de mayo. Las clases tendr\u00e1n lugar dos veces por semana, de 10:00 a 13:30 y se impartir\u00e1n de forma presencial en el centro BBK Sasoiko de Bilbao (C\/Ronda, s\/n). Las plazas est\u00e1n limitadas a 30 personas y se adjudicar\u00e1n en orden de inscripci\u00f3n. El coste de la matr\u00edcula es de 180 \u20ac y BBK ha establecido un sistema de ayudas para que ninguna persona interesada se quede fuera por motivos econ\u00f3micos. AGEKIN SASOIKO nace con la vocaci\u00f3n de ser replicada en otros centros BBK pr\u00f3ximamente.<\/p>\n<p>Desde BBK Sasoiko explican que \u201c<em>el autocuidado es una de las asignaturas que nos van quedando pendientes a lo largo de la vida; parece que nunca hay tiempo para ello. Una vez finalizada la vida laboral no podemos seguir poniendo excusas: la realidad es que cada vez vivimos m\u00e1s tiempo y, para poder disfrutar de esta etapa tenemos que tomar la responsabilidad de nuestro propio bienestar y aprender a cuidarnos. No debemos dejarnos envejecer.<\/em>\u201d.<\/p>\n<p>El programa Agekin Sasoiko propone nuevas materias y nuevas formas de aprender, acordes a los nuevos tiempos y a las necesidades de un colectivo cada vez m\u00e1s amplio, diverso y que poco o nada tiene que ver con el de los mayores de hace escasas d\u00e9cadas. \u201c<em>Tenemos por delante el desaf\u00edo de <\/em><em>llegar a un p\u00fablico poco habituado a relacionar la etapa de la jubilaci\u00f3n con procesos de aprendizaje, menos a\u00fan a un aprendizaje relacionado con necesidades de la vida diaria\u201d, <\/em>explica Gorka Mart\u00ednez. El mercado laboral es lo que marca las elecciones de estudios a lo largo de la vida: primero para acceder a \u00e9l, despu\u00e9s para mantenerse o mejorar.\u00a0 Una vez cerrada la etapa laboral, hoy d\u00eda existen numerosas opciones de ocio formativo; ahora, Agekin Sasoiko llega con la primera propuesta integral para afrontar la asignatura m\u00e1s importante, cuidar de uno mismo o una misma.<\/p>\n<p>En ese sentido, BBK ha dise\u00f1ado una formaci\u00f3n muy pr\u00e1ctica, acorde a las nuevas metodolog\u00edas de ense\u00f1anza que siguen el modelo de aprender haciendo. Es la mejor manera de integrar conocimientos y as\u00ed, adem\u00e1s, alejar\u00a0 algunos fantasmas.\u00a0 Es el caso del conocido \u201ces que soy ya demasiado mayor para aprender\u201d que preocupa a algunas personas mayores.\u00a0 Eso s\u00ed, la treintena de alumnos y alumnas de esta primera promoci\u00f3n de Agekin Sasoiko, terminar\u00e1n su formaci\u00f3n realizando en grupo un trabajo de fin de curso relacionado con alguna de las cuestiones planteadas a lo largo de la formaci\u00f3n.<\/p>\n<p><a href=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/proyectos\/agekin-sasoiko\/\">M\u00c1S INFORMACI\u00d3N<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o, BBK propone a las personas mayores de 55  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[567],"tags":[],"class_list":["post-19206","post","type-post","status-publish","format-standard","hentry","category-personas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso - Actualidad - BBK<\/title>\n<meta name=\"description\" content=\"Este a\u00f1o, BBK propone a las personas mayores de 55 a\u00f1os que han finalizado su etapa laboral volver a las aulas para estudiar la lecci\u00f3n m\u00e1s importante:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso - Actualidad - BBK\" \/>\n<meta property=\"og:description\" content=\"Este a\u00f1o, BBK propone a las personas mayores de 55 a\u00f1os que han finalizado su etapa laboral volver a las aulas para estudiar la lecci\u00f3n m\u00e1s importante:\" \/>\n<meta property=\"og:url\" content=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/\" \/>\n<meta property=\"og:site_name\" content=\"BBK\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBKeus?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-13T10:41:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T16:12:22+00:00\" \/>\n<meta name=\"author\" content=\"\u00darsula L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:site\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00darsula L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\\\/\"},\"author\":{\"name\":\"\u00darsula L\u00f3pez\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/317821b3a0d0178af253b98b08027fda\"},\"headline\":\"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso\",\"datePublished\":\"2022-09-13T10:41:04+00:00\",\"dateModified\":\"2026-06-18T16:12:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\\\/\"},\"wordCount\":653,\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"articleSection\":[\"Personas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\\\/\",\"name\":\"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso - Actualidad - BBK\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\"},\"datePublished\":\"2022-09-13T10:41:04+00:00\",\"dateModified\":\"2026-06-18T16:12:22+00:00\",\"description\":\"Este a\u00f1o, BBK propone a las personas mayores de 55 a\u00f1os que han finalizado su etapa laboral volver a las aulas para estudiar la lecci\u00f3n m\u00e1s importante:\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"name\":\"BBK\",\"description\":\"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.\",\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\",\"name\":\"BBK Fundazioa\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"contentUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"width\":1845,\"height\":784,\"caption\":\"BBK Fundazioa\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BBKeus?fref=ts\",\"https:\\\/\\\/x.com\\\/BBK_eus\",\"https:\\\/\\\/www.instagram.com\\\/bbk_eus\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BBKwebTV\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-bbk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/317821b3a0d0178af253b98b08027fda\",\"name\":\"\u00darsula L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"caption\":\"\u00darsula L\u00f3pez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso - Actualidad - BBK","description":"Este a\u00f1o, BBK propone a las personas mayores de 55 a\u00f1os que han finalizado su etapa laboral volver a las aulas para estudiar la lecci\u00f3n m\u00e1s importante:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/","og_locale":"es_ES","og_type":"article","og_title":"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso - Actualidad - BBK","og_description":"Este a\u00f1o, BBK propone a las personas mayores de 55 a\u00f1os que han finalizado su etapa laboral volver a las aulas para estudiar la lecci\u00f3n m\u00e1s importante:","og_url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/","og_site_name":"BBK","article_publisher":"https:\/\/www.facebook.com\/BBKeus?fref=ts","article_published_time":"2022-09-13T10:41:04+00:00","article_modified_time":"2026-06-18T16:12:22+00:00","author":"\u00darsula L\u00f3pez","twitter_card":"summary_large_image","twitter_creator":"@BBK_eus","twitter_site":"@BBK_eus","twitter_misc":{"Escrito por":"\u00darsula L\u00f3pez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/#article","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/"},"author":{"name":"\u00darsula L\u00f3pez","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/317821b3a0d0178af253b98b08027fda"},"headline":"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso","datePublished":"2022-09-13T10:41:04+00:00","dateModified":"2026-06-18T16:12:22+00:00","mainEntityOfPage":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/"},"wordCount":653,"publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"articleSection":["Personas"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/","name":"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso - Actualidad - BBK","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website"},"datePublished":"2022-09-13T10:41:04+00:00","dateModified":"2026-06-18T16:12:22+00:00","description":"Este a\u00f1o, BBK propone a las personas mayores de 55 a\u00f1os que han finalizado su etapa laboral volver a las aulas para estudiar la lecci\u00f3n m\u00e1s importante:","breadcrumb":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/aprender-a-cuidarse-para-vivir-mejor-la-asignatura-mas-importante-del-nuevo-curso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aprender a cuidarse para vivir mejor, la asignatura m\u00e1s importante del nuevo curso"}]},{"@type":"WebSite","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","name":"BBK","description":"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.","publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization","name":"BBK Fundazioa","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","contentUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","width":1845,"height":784,"caption":"BBK Fundazioa"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BBKeus?fref=ts","https:\/\/x.com\/BBK_eus","https:\/\/www.instagram.com\/bbk_eus\/?hl=es","https:\/\/www.youtube.com\/user\/BBKwebTV","https:\/\/www.linkedin.com\/company\/fundacion-bbk\/"]},{"@type":"Person","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/317821b3a0d0178af253b98b08027fda","name":"\u00darsula L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","caption":"\u00darsula L\u00f3pez"}}]}},"_links":{"self":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/19206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/comments?post=19206"}],"version-history":[{"count":0,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/19206\/revisions"}],"wp:attachment":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/media?parent=19206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/categories?post=19206"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/tags?post=19206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}