{"id":19370,"date":"2022-09-30T09:35:37","date_gmt":"2022-09-30T07:35:37","guid":{"rendered":"\/"},"modified":"2026-06-18T18:11:55","modified_gmt":"2026-06-18T16:11:55","slug":"los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales","status":"publish","type":"post","link":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/","title":{"rendered":"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales"},"content":{"rendered":"<p>30\/09\/2022<\/p>\n<p>La segunda edici\u00f3n del certamen literario BBK Sasoiko ya tiene ganadores: \u2018Ane\u2019, de <strong>Enrique Garc\u00eda<\/strong> y \u2018Esperientzia ahaztezina\u2019, de <strong>Jes\u00fas Sesar<\/strong> han sido los trabajos seleccionados por el jurado en esta iniciativa que busca favorecer la participaci\u00f3n social de personas adultas mayores de 55 a\u00f1os a trav\u00e9s de la escritura.\u00a0 Los ganadores han recibido hoy sus premios en un acto celebrado en el espacio de la calle Ronda de BBK Sasoiko en Bilbao, donde han estado acompa\u00f1ados por numerosas personas de la comunidad Sasoiko.<\/p>\n<p>El fallo del jurado \u2013 integrado por personas que anteriormente han asistido a talleres de lectura y escritura en Sasoiko, y se han hecho cargo de la organizaci\u00f3n del certamen \u2013 ha destacado la capacidad de ambos trabajos para \u201c<em>visibilizar las relaciones intergeneracionales de manera muy actual<\/em>\u201d, as\u00ed como de despertar \u201c<em>sentimientos muy humanos<\/em>\u201d.<\/p>\n<p>Adem\u00e1s, ha concedido un acc\u00e9sit a <strong>Katy Parra<\/strong> por su relato \u2018Estrellas Africanas\u2019 y a <strong>Alazne D\u00edez<\/strong> por \u00a0\u2018Haurtzaroa: Ibilaldi Laburra\u2019, detacando las historias \u201c<em>reales y cercanas<\/em>\u201d que han sabido transmitir.<\/p>\n<p>Durante la entrega de premios, <strong>Ixone Zubieta<\/strong>, responsable de Personas de BBK, ha destacado que \u201c<em>este concurso <\/em><em>permite a las personas adultas mayores aportar su visi\u00f3n acerca de dos temas que les afectan de pleno como son el envejecimiento activo y las relaciones intergeneracionales, de forma creativa a trav\u00e9s de la escritura; ayuda, adem\u00e1s, a que nuestra sociedad reflexiones sobre estas dos cuestiones, en las que tenemos mucho por hacer<\/em>\u201d.<\/p>\n<p>Bilbao ha recordado tambi\u00e9n que \u201c<em>favorecer la conexi\u00f3n entre personas de distintas generaciones ha estado siempre entre los objetivos de la Fundaci\u00f3n BBK<\/em>\u201d. Ahora, en el marco de los Objetivos de Desarrollo Sostenible de la Agenda 2030 que la entidad asume dentro de su estrategia corporativa, es un aspecto al que la entidad quiere dar un impulso transversal.<\/p>\n<p>Los galardones del concurso \u2018Despertar de la escritura\u2019 se han entregado hoy con motivo del D\u00eda Internacional de las Personas Mayores que se celebra ma\u00f1ana, 1 de octubre.\u00a0 Tambi\u00e9n con este motivo, durante toda la semana BBK Sasoiko acoge la exposici\u00f3n \u2018historias de vida de las Personas Mayores \u2018 una muestra protagonizada por personas nonagenarias y centenarias de Bizkaia que es fruto de un proyecto de colaboraci\u00f3n de BBK Sasoiko con el dibujante Ander Elgorriaga (DibujaTolrato sin Parar) y la cineasta\u00a0Liannys Badillo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2018Ane\u2019, de Enrique Garc\u00eda y \u2018Esperientzia ahaztezina\u2019, de Jes\u00fas Sesar, han sido los trabajos seleccionados por el jurado<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[567],"tags":[],"class_list":["post-19370","post","type-post","status-publish","format-standard","hentry","category-personas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales - Actualidad - BBK<\/title>\n<meta name=\"description\" content=\"\u2018Ane\u2019, de Enrique Garc\u00eda y \u2018Esperientzia ahaztezina\u2019, de Jes\u00fas Sesar, han sido los trabajos seleccionados por el jurado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales - Actualidad - BBK\" \/>\n<meta property=\"og:description\" content=\"\u2018Ane\u2019, de Enrique Garc\u00eda y \u2018Esperientzia ahaztezina\u2019, de Jes\u00fas Sesar, han sido los trabajos seleccionados por el jurado\" \/>\n<meta property=\"og:url\" content=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/\" \/>\n<meta property=\"og:site_name\" content=\"BBK\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBKeus?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-30T07:35:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T16:11:55+00:00\" \/>\n<meta name=\"author\" content=\"Sonia Egea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:site\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia Egea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\\\/\"},\"author\":{\"name\":\"Sonia Egea\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/1e591116b03708dd7b1aa17bfe896d11\"},\"headline\":\"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales\",\"datePublished\":\"2022-09-30T07:35:37+00:00\",\"dateModified\":\"2026-06-18T16:11:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\\\/\"},\"wordCount\":404,\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"articleSection\":[\"Personas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\\\/\",\"name\":\"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales - Actualidad - BBK\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\"},\"datePublished\":\"2022-09-30T07:35:37+00:00\",\"dateModified\":\"2026-06-18T16:11:55+00:00\",\"description\":\"\u2018Ane\u2019, de Enrique Garc\u00eda y \u2018Esperientzia ahaztezina\u2019, de Jes\u00fas Sesar, han sido los trabajos seleccionados por el jurado\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"name\":\"BBK\",\"description\":\"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.\",\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\",\"name\":\"BBK Fundazioa\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"contentUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"width\":1845,\"height\":784,\"caption\":\"BBK Fundazioa\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BBKeus?fref=ts\",\"https:\\\/\\\/x.com\\\/BBK_eus\",\"https:\\\/\\\/www.instagram.com\\\/bbk_eus\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BBKwebTV\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-bbk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/1e591116b03708dd7b1aa17bfe896d11\",\"name\":\"Sonia Egea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x\",\"caption\":\"Sonia Egea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales - Actualidad - BBK","description":"\u2018Ane\u2019, de Enrique Garc\u00eda y \u2018Esperientzia ahaztezina\u2019, de Jes\u00fas Sesar, han sido los trabajos seleccionados por el jurado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/","og_locale":"es_ES","og_type":"article","og_title":"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales - Actualidad - BBK","og_description":"\u2018Ane\u2019, de Enrique Garc\u00eda y \u2018Esperientzia ahaztezina\u2019, de Jes\u00fas Sesar, han sido los trabajos seleccionados por el jurado","og_url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/","og_site_name":"BBK","article_publisher":"https:\/\/www.facebook.com\/BBKeus?fref=ts","article_published_time":"2022-09-30T07:35:37+00:00","article_modified_time":"2026-06-18T16:11:55+00:00","author":"Sonia Egea","twitter_card":"summary_large_image","twitter_creator":"@BBK_eus","twitter_site":"@BBK_eus","twitter_misc":{"Escrito por":"Sonia Egea","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/#article","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/"},"author":{"name":"Sonia Egea","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/1e591116b03708dd7b1aa17bfe896d11"},"headline":"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales","datePublished":"2022-09-30T07:35:37+00:00","dateModified":"2026-06-18T16:11:55+00:00","mainEntityOfPage":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/"},"wordCount":404,"publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"articleSection":["Personas"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/","name":"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales - Actualidad - BBK","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website"},"datePublished":"2022-09-30T07:35:37+00:00","dateModified":"2026-06-18T16:11:55+00:00","description":"\u2018Ane\u2019, de Enrique Garc\u00eda y \u2018Esperientzia ahaztezina\u2019, de Jes\u00fas Sesar, han sido los trabajos seleccionados por el jurado","breadcrumb":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/los-premios-bbk-sasoiko-visibilizan-las-relaciones-intergeneracionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los premios BBK Sasoiko visibilizan las relaciones intergeneracionales"}]},{"@type":"WebSite","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","name":"BBK","description":"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.","publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization","name":"BBK Fundazioa","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","contentUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","width":1845,"height":784,"caption":"BBK Fundazioa"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BBKeus?fref=ts","https:\/\/x.com\/BBK_eus","https:\/\/www.instagram.com\/bbk_eus\/?hl=es","https:\/\/www.youtube.com\/user\/BBKwebTV","https:\/\/www.linkedin.com\/company\/fundacion-bbk\/"]},{"@type":"Person","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/1e591116b03708dd7b1aa17bfe896d11","name":"Sonia Egea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e0a8514dedbc234c7a59dada52c66e2ae55980c384156a9359d0bbeba4d87f5?s=96&d=mm&r=x","caption":"Sonia Egea"}}]}},"_links":{"self":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/19370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/comments?post=19370"}],"version-history":[{"count":0,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/19370\/revisions"}],"wp:attachment":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/media?parent=19370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/categories?post=19370"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/tags?post=19370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}