{"id":26500,"date":"2023-10-27T09:57:46","date_gmt":"2023-10-27T07:57:46","guid":{"rendered":"\/"},"modified":"2025-05-29T14:27:20","modified_gmt":"2025-05-29T12:27:20","slug":"bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika","status":"publish","type":"post","link":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/","title":{"rendered":"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p class=\"primer_parrafo_noticia\">La feria del \u00faltimo lunes de Gernika tendr\u00e1 una novedad en esta edici\u00f3n del 2023.<\/p>\n<p>Y es que <strong>BBK Azoka presentar\u00e1 la iniciativa \u201cZenbat da?\u201d<\/strong>, una acci\u00f3n que consistir\u00e1 en implicar a las y los visitantes a la feria en un juego que pretende incrementar la venta de productos durante la feria adem\u00e1s de acercar el consumo y el conocimiento del producto y productores locales a la ciudadan\u00eda.<\/p>\n<p><strong>La acci\u00f3n consiste en que aquellas y aquellos que se acerquen al emplazamiento de BBK en la feria tendr\u00e1n que adivinar el precio exacto de un lote de productos de las y los baserritarras que tienen sus productos en BBK Azoka<\/strong>. <strong>La persona que se acerque al precio real (por abajo) del lote ser\u00e1 la ganadora del conjunto de productos expuestos.<\/strong><\/p>\n<p>Para participar en este juego, las y los interesados tendr\u00e1n que comprar un producto en cualquier puesto de venta agro-ganadera de la feria. Recibir\u00e1n un ticket que tendr\u00e1n que rellenar con sus datos y que deber\u00e1n introducirlo en una urna instalada en la zona de BBK junto al lote de productos. El d\u00eda 06 de noviembre se dar\u00e1 a conocer a la persona ganadora del lote de productos.<\/p>\n<p><strong>BBK Azoka<\/strong><\/p>\n<p><strong>BBK Azoka<\/strong> es un canal de venta online que permite al consumidor comprar productos agr\u00edcolas de primera calidad directamente a los agricultores y ganaderos vizca\u00ednos sin intermediarios. Adem\u00e1s, es una plataforma que busca dar a conocer el modelo de producci\u00f3n agraria de Bizkaia, basado en peque\u00f1as explotaciones en las que los baserritarras cuidan con mimo todos los pasos del proceso hasta conseguir el producto final.<\/p>\n<p>Adem\u00e1s, <strong>BBK Azoka<\/strong> es la f\u00f3rmula que permite compaginar una alimentaci\u00f3n slow y Km 0 con un ritmo de vida que a veces nos impide acudir a los mercados de forma habitual, as\u00ed como acercar nuestros productos a nuevas generaciones con h\u00e1bitos de compra nuevos o, simplemente, a personas que no tienen cerca de su domicilio la posibilidad de comprar en otros canales de venta directa.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa consistir\u00e1 en que las y los visitantes a la feria tendr\u00e1n que adivinar el precio exacto de un lote de productos de las y los baserritarras que tienen sus productos en BBK Azoka.<\/p>\n","protected":false},"author":3,"featured_media":2069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[478,568],"tags":[],"class_list":["post-26500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultura","category-medioambiente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika - Actualidad - BBK<\/title>\n<meta name=\"description\" content=\"La iniciativa consistir\u00e1 en que las y los visitantes a la feria tendr\u00e1n que adivinar el precio exacto de un lote de productos de las y los baserritarras que tienen sus productos en BBK Azoka.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika - Actualidad - BBK\" \/>\n<meta property=\"og:description\" content=\"La iniciativa consistir\u00e1 en que las y los visitantes a la feria tendr\u00e1n que adivinar el precio exacto de un lote de productos de las y los baserritarras que tienen sus productos en BBK Azoka.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/\" \/>\n<meta property=\"og:site_name\" content=\"BBK\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBKeus?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T07:57:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T12:27:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2018\/08\/plentzia-bbk-azoka-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00darsula L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:site\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00darsula L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/\"},\"author\":{\"name\":\"\u00darsula L\u00f3pez\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/317821b3a0d0178af253b98b08027fda\"},\"headline\":\"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika\",\"datePublished\":\"2023-10-27T07:57:46+00:00\",\"dateModified\":\"2025-05-29T12:27:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/\"},\"wordCount\":1117,\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/plentzia-bbk-azoka-01.jpg\",\"articleSection\":[\"Kultura\",\"Medioambiente\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/\",\"name\":\"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika - Actualidad - BBK\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/plentzia-bbk-azoka-01.jpg\",\"datePublished\":\"2023-10-27T07:57:46+00:00\",\"dateModified\":\"2025-05-29T12:27:20+00:00\",\"description\":\"La iniciativa consistir\u00e1 en que las y los visitantes a la feria tendr\u00e1n que adivinar el precio exacto de un lote de productos de las y los baserritarras que tienen sus productos en BBK Azoka.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/#primaryimage\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/plentzia-bbk-azoka-01.jpg\",\"contentUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/plentzia-bbk-azoka-01.jpg\",\"width\":1000,\"height\":662,\"caption\":\"Plentzia azoka\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"name\":\"BBK\",\"description\":\"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.\",\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\",\"name\":\"BBK Fundazioa\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"contentUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"width\":1845,\"height\":784,\"caption\":\"BBK Fundazioa\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BBKeus?fref=ts\",\"https:\\\/\\\/x.com\\\/BBK_eus\",\"https:\\\/\\\/www.instagram.com\\\/bbk_eus\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BBKwebTV\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-bbk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/317821b3a0d0178af253b98b08027fda\",\"name\":\"\u00darsula L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"caption\":\"\u00darsula L\u00f3pez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika - Actualidad - BBK","description":"La iniciativa consistir\u00e1 en que las y los visitantes a la feria tendr\u00e1n que adivinar el precio exacto de un lote de productos de las y los baserritarras que tienen sus productos en BBK Azoka.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/","og_locale":"es_ES","og_type":"article","og_title":"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika - Actualidad - BBK","og_description":"La iniciativa consistir\u00e1 en que las y los visitantes a la feria tendr\u00e1n que adivinar el precio exacto de un lote de productos de las y los baserritarras que tienen sus productos en BBK Azoka.","og_url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/","og_site_name":"BBK","article_publisher":"https:\/\/www.facebook.com\/BBKeus?fref=ts","article_published_time":"2023-10-27T07:57:46+00:00","article_modified_time":"2025-05-29T12:27:20+00:00","og_image":[{"width":1000,"height":662,"url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2018\/08\/plentzia-bbk-azoka-01.jpg","type":"image\/jpeg"}],"author":"\u00darsula L\u00f3pez","twitter_card":"summary_large_image","twitter_creator":"@BBK_eus","twitter_site":"@BBK_eus","twitter_misc":{"Escrito por":"\u00darsula L\u00f3pez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/#article","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/"},"author":{"name":"\u00darsula L\u00f3pez","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/317821b3a0d0178af253b98b08027fda"},"headline":"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika","datePublished":"2023-10-27T07:57:46+00:00","dateModified":"2025-05-29T12:27:20+00:00","mainEntityOfPage":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/"},"wordCount":1117,"publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/#primaryimage"},"thumbnailUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2018\/08\/plentzia-bbk-azoka-01.jpg","articleSection":["Kultura","Medioambiente"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/","name":"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika - Actualidad - BBK","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/#primaryimage"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/#primaryimage"},"thumbnailUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2018\/08\/plentzia-bbk-azoka-01.jpg","datePublished":"2023-10-27T07:57:46+00:00","dateModified":"2025-05-29T12:27:20+00:00","description":"La iniciativa consistir\u00e1 en que las y los visitantes a la feria tendr\u00e1n que adivinar el precio exacto de un lote de productos de las y los baserritarras que tienen sus productos en BBK Azoka.","breadcrumb":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/#primaryimage","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2018\/08\/plentzia-bbk-azoka-01.jpg","contentUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2018\/08\/plentzia-bbk-azoka-01.jpg","width":1000,"height":662,"caption":"Plentzia azoka"},{"@type":"BreadcrumbList","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/bbk-azoka-presenta-la-iniciativa-zenbat-da-en-la-popular-feria-del-ultimo-lunes-de-gernika\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/"},{"@type":"ListItem","position":2,"name":"BBK Azoka presenta la iniciativa \u201cZenbat da?\u201d en la popular feria del \u00faltimo lunes de Gernika"}]},{"@type":"WebSite","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","name":"BBK","description":"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.","publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization","name":"BBK Fundazioa","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","contentUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","width":1845,"height":784,"caption":"BBK Fundazioa"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BBKeus?fref=ts","https:\/\/x.com\/BBK_eus","https:\/\/www.instagram.com\/bbk_eus\/?hl=es","https:\/\/www.youtube.com\/user\/BBKwebTV","https:\/\/www.linkedin.com\/company\/fundacion-bbk\/"]},{"@type":"Person","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/317821b3a0d0178af253b98b08027fda","name":"\u00darsula L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","caption":"\u00darsula L\u00f3pez"}}]}},"_links":{"self":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/26500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/comments?post=26500"}],"version-history":[{"count":0,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/26500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/media\/2069"}],"wp:attachment":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/media?parent=26500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/categories?post=26500"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/tags?post=26500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}