{"id":29857,"date":"2024-02-14T13:01:50","date_gmt":"2024-02-14T12:01:50","guid":{"rendered":"\/"},"modified":"2025-05-29T14:26:00","modified_gmt":"2025-05-29T12:26:00","slug":"arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes","status":"publish","type":"post","link":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/","title":{"rendered":"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p class=\"primer_parrafo_noticia\">BBK ha puesto en marcha la primera edici\u00f3n de PACT BY BBK, una iniciativa que busca favorecer el buen trato en las relaciones afectivas y afectivo-sexuales de las y los adolescentes de Bizkaia.<\/p>\n<p>Dirigida a j\u00f3venes de entre 15 y 17 a\u00f1os, el programa invita a los y las j\u00f3venes a actuar para cambiar el guion de historias que a menudo desembocan en desigualdad y violencia, ofreciendo aprendizaje, experiencia y acuerdos, a trav\u00e9s de sesiones din\u00e1micas y experienciales, todo ello desde un enfoque de educaci\u00f3n sexual feminista integral.<\/p>\n<p>Durante los pr\u00f3ximos meses, PACT BY BBK ofrecer\u00e1 sesiones din\u00e1micas dirigidas a grupos peque\u00f1os, en las que j\u00f3venes y adolescentes podr\u00e1n explorar, con su grupo de tiempo libre o con su equipo deportivo, temas como el autoconcepto, el autocuidado en las relaciones y la b\u00fasqueda de consenso y compromiso en la construcci\u00f3n de relaciones sanas y de buen amor. Adaptadas a cada edad, las actividades est\u00e1n dirigidas a promover el compromiso con la igualdad y el buen trato entre j\u00f3venes. Todo este proceso se concreta en los Acuerdos por los Buenos Tratos, una experiencia de consenso basada en pactos que refuerza el empoderamiento entre iguales.<\/p>\n<p>El programa incluye cinco sesiones din\u00e1micas y experienciales y una sexta sesi\u00f3n festiva que se llevar\u00e1 a cabo con la sex\u00f3loga Isa Duque (Psico Woman en Youtube e Instagram), en junio de 2024, en la Sala BBK.<\/p>\n<p>Asimismo, durante esta primera edici\u00f3n, PACT BY BBK contar\u00e1 con la colaboraci\u00f3n de La Dram\u00e1tica Errante, compa\u00f1\u00eda de teatro dirigida por Maria Goiricelaya y Ane Pikaza, que trabajar\u00e1 conjuntamente en las sesiones con los j\u00f3venes para dar forma a la obra de teatro \u00abRomeo y Julieta. Generaci\u00f3n Z\u00bb, que se estrenar\u00e1 en la Sala BBK en 2025.<\/p>\n<p>El programa cuenta con la colaboraci\u00f3n de diversas entidades vizca\u00ednas que trabajan con adolescentes en el \u00e1mbito de la educaci\u00f3n no formal y el tiempo libre, como Norai, Fidias o Gorabide. Tambi\u00e9n se sumar\u00e1n ayuntamientos como Portugalete, Amorebieta, Barakaldo o Iurreta, entre otros.<\/p>\n<p>Todas aquellas entidades deportivas y de tiempo libre, as\u00ed como agentes que trabajan con j\u00f3venes y adolescentes en un entorno de ocio en Bizkaia interesados en este programa, pueden solicitar informaci\u00f3n escribiendo un correo electr\u00f3nico a\u00a0\u00a0proiektuak@bbk.eus.<\/p>\n<p>PACT BY BBK tiene su origen en una experiencia piloto que puso en marcha BBK el pasado a\u00f1o, en la que participaron 10 grupos de j\u00f3venes y adolescentes, compartiendo y contrastando metodolog\u00edas, contenidos y aprendizajes. Un programa piloto que se llev\u00f3 a cabo con la colaboraci\u00f3n de Athletic Fundazioa, Ayuntamiento de Barakaldo, Txispeleta Eskaut Taldea de Mungia y la Escuela Europea de Frankfurt.<\/p>\n<p><a href=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/personas-sociedad\/bbk-pact\/pact-by-bbk\/\">M\u00e1s informaci\u00f3n<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pact by BBK incluye una sesi\u00f3n festiva con la sex\u00f3loga Isa Duque (Psico Woman), en la Sala BBK y el montaje de la obra \u00abRomeo y Julieta. Generaci\u00f3n Z\u201d bajo la direcci\u00f3n de Mar\u00eda Goiricelaya y Ane Pikaza<\/p>\n","protected":false},"author":3,"featured_media":24623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[567],"tags":[],"class_list":["post-29857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes - Actualidad - BBK<\/title>\n<meta name=\"description\" content=\"Pact by BBK incluye una sesi\u00f3n festiva con la sex\u00f3loga Isa Duque (Psico Woman), en la Sala BBK y el montaje de la obra &quot;Romeo y Julieta. Generaci\u00f3n Z\u201d bajo la direcci\u00f3n de Mar\u00eda Goiricelaya y Ane Pikaza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes - Actualidad - BBK\" \/>\n<meta property=\"og:description\" content=\"Pact by BBK incluye una sesi\u00f3n festiva con la sex\u00f3loga Isa Duque (Psico Woman), en la Sala BBK y el montaje de la obra &quot;Romeo y Julieta. Generaci\u00f3n Z\u201d bajo la direcci\u00f3n de Mar\u00eda Goiricelaya y Ane Pikaza\" \/>\n<meta property=\"og:url\" content=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/\" \/>\n<meta property=\"og:site_name\" content=\"BBK\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BBKeus?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-14T12:01:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T12:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/01\/Pact_2023_BBK001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00darsula L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:site\" content=\"@BBK_eus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00darsula L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/\"},\"author\":{\"name\":\"\u00darsula L\u00f3pez\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/317821b3a0d0178af253b98b08027fda\"},\"headline\":\"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes\",\"datePublished\":\"2024-02-14T12:01:50+00:00\",\"dateModified\":\"2025-05-29T12:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/\"},\"wordCount\":1240,\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Pact_2023_BBK001.jpg\",\"articleSection\":[\"Personas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/\",\"name\":\"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes - Actualidad - BBK\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Pact_2023_BBK001.jpg\",\"datePublished\":\"2024-02-14T12:01:50+00:00\",\"dateModified\":\"2025-05-29T12:26:00+00:00\",\"description\":\"Pact by BBK incluye una sesi\u00f3n festiva con la sex\u00f3loga Isa Duque (Psico Woman), en la Sala BBK y el montaje de la obra \\\"Romeo y Julieta. Generaci\u00f3n Z\u201d bajo la direcci\u00f3n de Mar\u00eda Goiricelaya y Ane Pikaza\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/#primaryimage\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Pact_2023_BBK001.jpg\",\"contentUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Pact_2023_BBK001.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"name\":\"BBK\",\"description\":\"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.\",\"publisher\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#organization\",\"name\":\"BBK Fundazioa\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"contentUrl\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg\",\"width\":1845,\"height\":784,\"caption\":\"BBK Fundazioa\"},\"image\":{\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BBKeus?fref=ts\",\"https:\\\/\\\/x.com\\\/BBK_eus\",\"https:\\\/\\\/www.instagram.com\\\/bbk_eus\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BBKwebTV\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-bbk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\\\/es\\\/#\\\/schema\\\/person\\\/317821b3a0d0178af253b98b08027fda\",\"name\":\"\u00darsula L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x\",\"caption\":\"\u00darsula L\u00f3pez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes - Actualidad - BBK","description":"Pact by BBK incluye una sesi\u00f3n festiva con la sex\u00f3loga Isa Duque (Psico Woman), en la Sala BBK y el montaje de la obra \"Romeo y Julieta. Generaci\u00f3n Z\u201d bajo la direcci\u00f3n de Mar\u00eda Goiricelaya y Ane Pikaza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/","og_locale":"es_ES","og_type":"article","og_title":"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes - Actualidad - BBK","og_description":"Pact by BBK incluye una sesi\u00f3n festiva con la sex\u00f3loga Isa Duque (Psico Woman), en la Sala BBK y el montaje de la obra \"Romeo y Julieta. Generaci\u00f3n Z\u201d bajo la direcci\u00f3n de Mar\u00eda Goiricelaya y Ane Pikaza","og_url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/","og_site_name":"BBK","article_publisher":"https:\/\/www.facebook.com\/BBKeus?fref=ts","article_published_time":"2024-02-14T12:01:50+00:00","article_modified_time":"2025-05-29T12:26:00+00:00","og_image":[{"width":1200,"height":800,"url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/01\/Pact_2023_BBK001.jpg","type":"image\/jpeg"}],"author":"\u00darsula L\u00f3pez","twitter_card":"summary_large_image","twitter_creator":"@BBK_eus","twitter_site":"@BBK_eus","twitter_misc":{"Escrito por":"\u00darsula L\u00f3pez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/#article","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/"},"author":{"name":"\u00darsula L\u00f3pez","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/317821b3a0d0178af253b98b08027fda"},"headline":"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes","datePublished":"2024-02-14T12:01:50+00:00","dateModified":"2025-05-29T12:26:00+00:00","mainEntityOfPage":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/"},"wordCount":1240,"publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/#primaryimage"},"thumbnailUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/01\/Pact_2023_BBK001.jpg","articleSection":["Personas"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/","name":"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes - Actualidad - BBK","isPartOf":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/#primaryimage"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/#primaryimage"},"thumbnailUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/01\/Pact_2023_BBK001.jpg","datePublished":"2024-02-14T12:01:50+00:00","dateModified":"2025-05-29T12:26:00+00:00","description":"Pact by BBK incluye una sesi\u00f3n festiva con la sex\u00f3loga Isa Duque (Psico Woman), en la Sala BBK y el montaje de la obra \"Romeo y Julieta. Generaci\u00f3n Z\u201d bajo la direcci\u00f3n de Mar\u00eda Goiricelaya y Ane Pikaza","breadcrumb":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/#primaryimage","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/01\/Pact_2023_BBK001.jpg","contentUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/01\/Pact_2023_BBK001.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/arranca-pact-by-bbk-talleres-para-favorecer-la-igualdad-y-el-buen-trato-entro-los-y-las-adolescentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/"},{"@type":"ListItem","position":2,"name":"Arranca PACT BY BBK, talleres para favorecer la igualdad y el buen trato entro los y las adolescentes"}]},{"@type":"WebSite","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#website","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","name":"BBK","description":"Actividades, proyectos sociales, \u00c1reas de actuaci\u00f3n, ideas para el futuro y presente de Bizkaia.","publisher":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#organization","name":"BBK Fundazioa","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/","url":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","contentUrl":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/wp-content\/uploads\/2023\/10\/LOGOTIPO-BBK_VERSION-PRINCIPAL_COLOR.jpg","width":1845,"height":784,"caption":"BBK Fundazioa"},"image":{"@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BBKeus?fref=ts","https:\/\/x.com\/BBK_eus","https:\/\/www.instagram.com\/bbk_eus\/?hl=es","https:\/\/www.youtube.com\/user\/BBKwebTV","https:\/\/www.linkedin.com\/company\/fundacion-bbk\/"]},{"@type":"Person","@id":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/#\/schema\/person\/317821b3a0d0178af253b98b08027fda","name":"\u00darsula L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce4be3bc3fe9ab01bb925e70f0b9b1d9a8e1a1c962b10cee5b67be40326c25ce?s=96&d=mm&r=x","caption":"\u00darsula L\u00f3pez"}}]}},"_links":{"self":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/29857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/comments?post=29857"}],"version-history":[{"count":0,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/29857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/media\/24623"}],"wp:attachment":[{"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/media?parent=29857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/categories?post=29857"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bbk-bbkeus-dev-781687585.eu-west-1.elb.amazonaws.com\/es\/wp-json\/wp\/v2\/tags?post=29857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}